{"id":1749,"date":"2023-11-12T20:37:29","date_gmt":"2023-11-13T01:37:34","guid":{"rendered":"https:\/\/intiqahotel.com\/intiqa-new2\/suite-junior-3\/"},"modified":"2023-11-21T15:54:23","modified_gmt":"2023-11-21T20:54:23","slug":"habitacion-matrimonial","status":"publish","type":"page","link":"https:\/\/intiqahotel.com\/en\/habitaciones\/habitacion-matrimonial\/","title":{"rendered":"Double Room"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-4d8a2e6f alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<h1 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color wp-elements-76bfd8518b601584721a3c706057cd04\"><strong>Double Room<\/strong><\/h1>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-887a0016 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div data-aos= \"flip-up\" data-aos-duration=\"400\" data-aos-delay=\"100\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-info-box uagb-block-e8ce4646 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong>Live the experience Intiqa<\/strong><\/h3><\/div><p class=\"uagb-ifb-desc\">Our rooms are much more than a place to<br>rest; they are a reflection of the cultural wealth of Puno.<br>Decoradas con \u00edconos de la cultura Pucar\u00e1 y Tiahuanaco, cada<br>one is a space where comfort and authenticity<br>fuse to provide a unique experience.<br><br>Our hotel offers services of the internet, along with exquisite<br>dining options at our restaurant and moments of<br>entertainment in our bar.<\/p><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-284aab73 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div data-aos= \"zoom-in\" data-aos-duration=\"400\" data-aos-delay=\"500\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-image aligncenter uagb-block-9c86bd1f wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/ICONOS-02.png ,https:\/\/intiqahotel.com\/wp-content\/uploads\/ICONOS-02.png 780w, https:\/\/intiqahotel.com\/wp-content\/uploads\/ICONOS-02.png 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/ICONOS-02.png\" alt=\"\" class=\"uag-image-748\" width=\"141\" height=\"67\" title=\"\" loading=\"lazy\"\/><\/figure><\/div>\n\n\n\n<div data-aos= \"zoom-in-down\" data-aos-duration=\"400\" data-aos-delay=\"500\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-advanced-heading uagb-block-1064c54e\"><h2 class=\"uagb-heading-text\"><strong>Double Room<\/strong><\/h2><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0464bdde alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div data-aos= \"flip-right\" data-aos-duration=\"400\" data-aos-delay=\"300\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-info-box uagb-block-502f40bb uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/icono-logo-40-150x150.png\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong>Cultural Richness<\/strong><\/h3><\/div><p class=\"uagb-ifb-desc\">Decoradas con \u00edconos Pucar\u00e1<br>and Tiahuanaco, reflecting the<br>authenticity and culture of<br>Puno.<\/p><\/div><\/div>\n\n\n\n<div data-aos= \"flip-right\" data-aos-duration=\"400\" data-aos-delay=\"600\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-info-box uagb-block-c1b6efa3 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/ICONOS-41-150x150.png\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong>Comfort Authentic<\/strong><\/h3><\/div><p class=\"uagb-ifb-desc\">Down comforters<br>goose and floors thermal<br>hypoallergenic guarantee<br>rest is exceptional.<\/p><\/div><\/div>\n\n\n\n<div data-aos= \"flip-right\" data-aos-duration=\"400\" data-aos-delay=\"900\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-info-box uagb-block-09c33d2e uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/icono-05-05-150x132.png\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong>Elegance<br>Eco-Friendly<\/strong><\/h3><\/div><p class=\"uagb-ifb-desc\">Habitaci\u00f3n amplia con calefacci\u00f3n<br>solar and electric,<br>committed to reduce<br>the environmental impact.<\/p><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div data-aos= \"flip-right\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-53c34ca2 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-83e86dd4\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--grid spectra-image-gallery__layout--grid-col-2 spectra-image-gallery__layout--grid-col-tab-4 spectra-image-gallery__layout--grid-col-mob-4\">\n\t\t\t\t\t\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='1854'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2-1024x683.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2-300x200.jpg\" alt=\"hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='1834'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral-1024x683.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral-300x200.jpg\" alt=\"hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='1835'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-bano.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-bano-683x1024.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-bano-200x300.jpg\" alt=\"hotel-intiqa-puno-peru-habitacion-matrimonial-ba\u00f1o\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='1838'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet-1024x683.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet-300x200.jpg\" alt=\"hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='1837'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion-1024x683.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion-300x200.jpg\" alt=\"hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='1836'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--grid\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-mesa.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-mesa-1024x683.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--grid\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-mesa-300x200.jpg\" alt=\"hotel-intiqa-puno-peru-habitacion-matrimonial-mesa\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class='spectra-image-gallery__control-lightbox' tabindex='0'>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper spectra-image-gallery__control-lightbox--main\" dir=\"\">\n\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2.jpg\" alt=\"hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral.jpg\" alt=\"hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-bano.jpg\" alt=\"hotel-intiqa-puno-peru-habitacion-matrimonial-ba\u00f1o\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet.jpg\" alt=\"hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion.jpg\" alt=\"hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-mesa.jpg\" alt=\"hotel-intiqa-puno-peru-habitacion-matrimonial-mesa\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t\t\t<\/div>\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button class='spectra-image-gallery__control-lightbox--close'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-70fc3136 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5959325e animated backInRight delay-500ms\"><h2 class=\"uagb-heading-text\"><strong>Our<br>acknowledgements<\/strong><\/h2><\/div>\n\n\n\n<p class=\"has-text-align-center animated backInLeft delay-500ms has-white-color has-text-color\" style=\"font-size:20px;line-height:1.2\">In Intiqa, we are honored to have received the certificate<br>of excellence from TripAdvisor, a reflection of our<br>commitment to quality and the satisfaction of<br>our guests. Thank you to the community<br>of travellers for recognizing our efforts and<br>passion.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-1d75eb49 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-eff79e42\">\n<div data-aos= \"fade-right\" data-aos-duration=\"400\" data-aos-delay=\"500\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-image uagb-block-15780b06 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2016.png ,https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2016.png 780w, https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2016.png 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2016.png\" alt=\"\" class=\"uag-image-897\" width=\"201\" height=\"211\" title=\"\" loading=\"lazy\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-7e9c86a8\">\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"500\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-image uagb-block-2c7fe1a1 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2017.png ,https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2017.png 780w, https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2017.png 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2017.png\" alt=\"\" class=\"uag-image-898\" width=\"195\" height=\"200\" title=\"\" loading=\"lazy\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6a3f8e6a\">\n<div data-aos= \"fade-up\" data-aos-duration=\"400\" data-aos-delay=\"500\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-image uagb-block-b49db76c wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2018.png ,https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2018.png 780w, https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2018.png 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2018.png\" alt=\"\" class=\"uag-image-899\" width=\"191\" height=\"195\" title=\"\" loading=\"lazy\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0f60086f\">\n<div data-aos= \"fade-left\" data-aos-duration=\"400\" data-aos-delay=\"500\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-image uagb-block-14d7bd72 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2019.png ,https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2019.png 780w, https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2019.png 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-reconocimientos-tripadvisor-2019.png\" alt=\"\" class=\"uag-image-900\" width=\"186\" height=\"195\" title=\"\" loading=\"lazy\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Habitaci\u00f3n Matrimonial Habitaci\u00f3n Matrimonial Nuestrosreconocimientos En Intiqa, nos honra haber recibido el certificadode excelencia de TripAdvisor, reflejo de nuestrocompromiso con la calidad y la satisfacci\u00f3n denuestros hu\u00e9spedes. Agradecemos a la comunidadde viajeros por reconocer nuestro esfuerzo ypasi\u00f3n.<\/p>","protected":false},"author":1,"featured_media":0,"parent":1390,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_mo_disable_npp":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"spectra_custom_meta":{"_edit_lock":["1773249624:2"],"footnotes":[""],"_uag_custom_page_level_css":[""],"ast-site-content-layout":["full-width-container"],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"astra-migrate-meta-layouts":["set"],"_joinchat":["a:0:{}"],"site-post-title":["disabled"],"_edit_last":["2"],"_wp_page_template":["default"],"_nested_pages_status":["show"],"_np_nav_status":["show"],"_np_nav_title":[""],"_np_link_target":[""],"_np_title_attribute":[""],"_np_nav_css_classes":[""],"_np_nav_custom_url":[""],"_uag_page_assets":["a:9:{s:3:\"css\";s:124804:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:0.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-uagb-image):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}\n.uagb-ifb-content>svg *{-webkit-transition:all 0.2s;-o-transition:all 0.2s;transition:all 0.2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .wp-block-button__link svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}\n.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow 0.2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:0.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:0.2;background:rgba(0,0,0,0.5);transition:opacity 0.35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:0.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform 0.35s, opacity 0.35s ease-in-out;transform:translate3d(0, 24px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform 0.4s, opacity 0.4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform 0.45s, opacity 0.45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform 0.35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform 0.35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:0.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:0.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}\n.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all 0.3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}\n\ufeff.wp-block-uagb-image-gallery{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;-webkit-justify-content:center;justify-content:center;flex-direction:column}.spectra-image-gallery *{box-sizing:border-box}.spectra-image-gallery__layout--grid{display:-moz-grid;display:-ms-grid;display:grid;grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--grid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:transparent}.spectra-image-gallery__layout--isogrid-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--isogrid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:transparent}.spectra-image-gallery__layout--masonry-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--carousel{width:100%}.spectra-image-gallery__layout--carousel .slick-initialized{visibility:visible}.spectra-image-gallery__layout--carousel .slick-track{display:flex;align-items:center}.spectra-image-gallery__layout--carousel .slick-dots{padding:0;position:relative !important}.spectra-image-gallery__layout--carousel .slick-dots li button{padding:0}.spectra-image-gallery__layout--carousel .uagb-slick-carousel{padding:0}.spectra-image-gallery__layout--tiled{position:relative;display:grid;grid-auto-flow:dense;min-height:0;min-width:0}.spectra-image-gallery__layout--tiled-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__media{position:relative;overflow:hidden;-webkit-transition:box-shadow 0.25s;-moz-transition:box-shadow 0.25s;-o-transition:box-shadow 0.25s;transition:box-shadow 0.25s}.spectra-image-gallery__media--flagged{cursor:not-allowed}.spectra-image-gallery__media--clickable{cursor:pointer}.spectra-image-gallery__media--grid{aspect-ratio:1}.spectra-image-gallery__media--masonry{width:100%}.spectra-image-gallery__media--carousel{width:100%}.spectra-image-gallery__media--tiled{aspect-ratio:1;display:flex;align-items:center;justify-content:center}.spectra-image-gallery__media--tiled-wide,.spectra-image-gallery__media--tiled-tall{aspect-ratio:unset;width:100%;height:100%}.spectra-image-gallery__media--tiled picture{width:100%;height:100%}.spectra-image-gallery__media-sizer{aspect-ratio:1}.spectra-image-gallery__media-wrapper{position:relative}.spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__control-focus{opacity:0.25}.spectra-image-gallery__media-thumbnail{vertical-align:middle;-webkit-transition:filter 0.5s, transform 0.5s;-moz-transition:filter 0.5s, transform 0.5s;-o-transition:filter 0.5s, transform 0.5s;transition:filter 0.5s, transform 0.5s}.spectra-image-gallery__media-thumbnail--grid{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail--masonry{width:100%}.spectra-image-gallery__media-thumbnail--carousel{width:100%}.spectra-image-gallery__media-thumbnail--tiled{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail-blurrer{position:absolute;top:0;left:0;width:100% !important;height:100% !important;-webkit-transition:box-shadow 0.25s, -webkit-backdrop-filter 0.5s;-moz-transition:box-shadow 0.25s, backdrop-filter 0.5s;-o-transition:box-shadow 0.25s, backdrop-filter 0.5s;transition:box-shadow 0.25s, backdrop-filter 0.5s}.spectra-image-gallery__media-thumbnail-caption{-webkit-transition-property:color, background-color, border-color;-moz-transition-property:color, background-color, border-color;-o-transition-property:color, background-color, border-color;transition-property:color, background-color, border-color;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__media-thumbnail-caption--overlay{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;height:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption--bar-inside{width:100%;overflow:hidden;padding:1em;max-height:90%}.spectra-image-gallery__media-thumbnail-caption--bar-outside{width:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption-wrapper{-webkit-transition:background-color 0.25s;-moz-transition:background-color 0.25s;-o-transition:background-color 0.25s;transition:background-color 0.25s}.spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{position:absolute;top:0;left:0;width:100%;height:100%}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{position:absolute;top:0;left:0;width:100%;height:100%;display:flex;overflow:hidden}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-outside{position:relative;width:100%;overflow:hidden}.spectra-image-gallery__control-wrapper{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;justify-content:center}.spectra-image-gallery__control-arrows{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;background-color:transparent;padding:0;cursor:pointer;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-arrows:disabled{opacity:0.25;cursor:initial}.spectra-image-gallery__control-arrows:focus{background-color:transparent}.spectra-image-gallery__control-arrows--grid{border:none}.spectra-image-gallery__control-arrows svg{-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-dots{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;padding:0 !important;margin:0 !important}.spectra-image-gallery__control-dots li{position:relative;display:inline-block;width:20px;height:20px;margin:0;padding:0;cursor:pointer;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-dots li:hover{transform:scale(1.5);background-color:transparent}.spectra-image-gallery__control-dots li button{font-size:0;line-height:0;display:block;box-sizing:border-box;width:20px;height:20px;padding:5px;cursor:pointer;color:transparent;border:0;outline:none;background:transparent;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-dots li button::before{font-family:none;font-size:30px;line-height:20px;position:absolute;top:0;left:0;width:20px;height:20px;content:\"\u2022\";text-align:center;opacity:0.25;-webkit-font-smoothing:antialiased;-moz-osx-font-smoothing:grayscale;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-dots li.spectra-image-gallery__control-dot--active button::before{opacity:0.75}.spectra-image-gallery__control-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.spectra-image-gallery__control-loader div{border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.spectra-image-gallery__control-button{cursor:pointer;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-button.disabled{opacity:0.25;pointer-events:none}.spectra-image-gallery__control-focus{cursor:pointer;position:absolute;box-sizing:content-box !important;top:0;right:0;width:1.5em;height:1.5em;padding:0.5em;background-color:transparent;border:none;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-focus:hover{opacity:1 !important}.spectra-image-gallery__control-focus svg{fill:#fff;filter:drop-shadow(1px 1px 1px rgba(0,0,0,0.5))}.spectra-image-gallery__control-lightbox{position:fixed;top:0;left:0;width:100vw !important;max-width:100vw !important;height:100vh !important;max-height:100vh !important;display:flex;flex-direction:column;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;z-index:999999999 !important;outline:none;margin-block-start:0;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-lightbox--main{width:100%;flex:1}.spectra-image-gallery__control-lightbox--main .swiper-slide{height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center}.spectra-image-gallery__control-lightbox--main .swiper-slide img{display:block;max-height:70%;max-width:80%}.spectra-image-gallery__control-lightbox--caption{position:absolute;bottom:0;left:0;width:100%;display:flex;align-items:center;justify-content:center;text-align:center}.spectra-image-gallery__control-lightbox--editor-link{-webkit-transition-property:color;-moz-transition-property:color;-o-transition-property:color;transition-property:color;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-lightbox--thumbnails{width:75%}.spectra-image-gallery__control-lightbox--thumbnails-wrapper{width:100%}.spectra-image-gallery__control-lightbox--thumbnails .swiper-wrapper{height:150px}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide{cursor:pointer;height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center;opacity:0.5;transform:scale(75%);-webkit-transition-property:opacity, transform;-moz-transition-property:opacity, transform;-o-transition-property:opacity, transform;transition-property:opacity, transform;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide-active{opacity:1;transform:scale(100%)}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide img{border-radius:3px}.spectra-image-gallery__control-lightbox--count{position:absolute;z-index:999}.spectra-image-gallery__control-lightbox--close{position:absolute;cursor:pointer;padding:0;background-color:transparent;border:none;outline:0;line-height:0;z-index:999}.spectra-image-gallery__control-lightbox--close:hover{background-color:transparent}.spectra-image-gallery__iso-ref-wrapper{-ms-overflow-style:none;scrollbar-width:none}.spectra-image-gallery__iso-ref-wrapper::-webkit-scrollbar{display:none}@media (max-width: 976px){.spectra-image-gallery__layout--grid-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}@media (max-width: 767px){.spectra-image-gallery__layout--grid-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}.entry-content .wp-block-uagb-image-gallery .uagb-image-gallery__link{text-decoration:none}body .wp-block-post-content>.wp-block-uagb-image-gallery+.spectra-image-gallery__control-lightbox{margin-block-start:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}\n.wp-block-uagb-container.uagb-is-root-container .uagb-block-4d8a2e6f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-4d8a2e6f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4d8a2e6f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4d8a2e6f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4d8a2e6f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4d8a2e6f .uagb-container__video-wrap video{opacity: 0.7;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4d8a2e6f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4d8a2e6f{min-height: 0px;box-shadow: 0px 0px   #00000070 ;padding-top: 24%;padding-bottom: 24%;padding-left: 0%;padding-right: 0%;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: fixed;background-image: url(https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2.jpg);;background-clip: padding-box;}.wp-block-uagb-container.uagb-block-4d8a2e6f::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: rgba(0,0,0,0.98);opacity: 0.3;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-887a0016{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-887a0016 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-887a0016 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-887a0016 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-887a0016 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-887a0016 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-887a0016 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 800px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-887a0016{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 100px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;border-color: inherit;background-color: var(u002du002dast-global-color-5);;}.uagb-block-e8ce4646 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e8ce4646 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-e8ce4646 .uagb-ifb-icon svg{fill: #333;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e8ce4646 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e8ce4646 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e8ce4646 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e8ce4646 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-e8ce4646 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e8ce4646 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e8ce4646 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-e8ce4646.wp-block-uagb-info-box .uagb-ifb-title{color: #04535c;margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-e8ce4646.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-e8ce4646 .uagb-ifb-separator{width: 80px;border-top-width: 4px;border-top-color: var(u002du002dast-global-color-0);border-top-style: solid;margin-bottom: 14px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-e8ce4646 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 80px;border-top-width: 4px;border-top-color: var(u002du002dast-global-color-0);border-top-style: solid;}.uagb-block-e8ce4646 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-e8ce4646 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e8ce4646 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-e8ce4646.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-e8ce4646.uagb-infobox__content-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-e8ce4646 .uagb-ifb-title{font-size: 38px;}.uagb-block-e8ce4646 .uagb-ifb-desc{font-size: 20px;line-height: 1.2em;}.uagb-block-e8ce4646 .uagb-ifb-title-prefix{font-weight: 700;font-size: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-284aab73{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-284aab73 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-284aab73 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-284aab73 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-284aab73 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-284aab73 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-284aab73 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-284aab73{box-shadow: 0px 0px   #00000070 ;padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;border-color: inherit;background-color: #04535c;;}.uagb-block-9c86bd1f.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-9c86bd1f .wp-block-uagb-image__figure{align-items: center;}.uagb-block-9c86bd1f.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9c86bd1f.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;text-align: center;}.uagb-block-9c86bd1f.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9c86bd1f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-9c86bd1f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-9c86bd1f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-9c86bd1f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-9c86bd1f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-9c86bd1f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-9c86bd1f.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-9c86bd1f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-9c86bd1f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-9c86bd1f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-9c86bd1f.wp-block-uagb-image--layout-default figure img:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9c86bd1f.wp-block-uagb-image--layout-overlay figure img:hover{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-advanced-heading.uagb-block-1064c54e.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-1064c54e.wp-block-uagb-advanced-heading {text-align: center;margin-top: -30px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: -20px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-1064c54e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1064c54e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1064c54e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1064c54e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1064c54e .uagb-heading-text{font-size: 46px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0464bdde{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-0464bdde .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0464bdde .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0464bdde .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0464bdde .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0464bdde .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0464bdde > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-0464bdde{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 30px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;border-color: inherit;background-color: #04535c;;}.uagb-block-502f40bb .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-502f40bb .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-502f40bb .uagb-ifb-icon svg{fill: #333;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-502f40bb .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-502f40bb .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-502f40bb .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-502f40bb .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-502f40bb .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-502f40bb .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-502f40bb.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-502f40bb .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-502f40bb.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 10px;}.uagb-block-502f40bb.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 20px;}.uagb-block-502f40bb .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-502f40bb .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-502f40bb .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-502f40bb .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-502f40bb .uagb-infobox__content-wrap{text-align: center;}.uagb-block-502f40bb.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-502f40bb .uagb-ifb-title{font-size: 2.1em;}.uagb-block-502f40bb .uagb-ifb-desc{font-size: 20px;line-height: 24px;}.uagb-block-c1b6efa3 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c1b6efa3 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-c1b6efa3 .uagb-ifb-icon svg{fill: #333;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c1b6efa3 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c1b6efa3 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c1b6efa3 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c1b6efa3 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c1b6efa3 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c1b6efa3 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c1b6efa3 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-c1b6efa3.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 10px;}.uagb-block-c1b6efa3.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 20px;}.uagb-block-c1b6efa3 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-c1b6efa3 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-c1b6efa3 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-c1b6efa3 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c1b6efa3 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-c1b6efa3.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-c1b6efa3 .uagb-ifb-title{font-size: 2.1em;}.uagb-block-c1b6efa3 .uagb-ifb-desc{font-size: 20px;line-height: 24px;}.uagb-block-09c33d2e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-09c33d2e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-09c33d2e .uagb-ifb-icon svg{fill: #333;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-09c33d2e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-09c33d2e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-09c33d2e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-09c33d2e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-09c33d2e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-09c33d2e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-09c33d2e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-09c33d2e.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 10px;}.uagb-block-09c33d2e.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 20px;}.uagb-block-09c33d2e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-09c33d2e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-09c33d2e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-09c33d2e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-09c33d2e .uagb-infobox__content-wrap{text-align: center;}.uagb-block-09c33d2e.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-09c33d2e .uagb-ifb-title{font-size: 2.1em;}.uagb-block-09c33d2e .uagb-ifb-desc{font-size: 20px;line-height: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-53c34ca2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-53c34ca2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-53c34ca2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-53c34ca2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-53c34ca2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-53c34ca2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-53c34ca2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-53c34ca2{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;border-color: inherit;}.uagb-block-83e86dd4.wp-block-uagb-image-gallery{padding: 0px 0px 0px 0px;}.uagb-block-83e86dd4 .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-83e86dd4 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-83e86dd4 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-83e86dd4 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-83e86dd4 .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-83e86dd4 .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-83e86dd4 .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-83e86dd4 .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-83e86dd4 .spectra-image-gallery__media{border-style: none;box-shadow: 0px 0px   ;}.uagb-block-83e86dd4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-83e86dd4 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-83e86dd4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-83e86dd4 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-83e86dd4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-83e86dd4 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-83e86dd4 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-83e86dd4 .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-83e86dd4 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-83e86dd4 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-83e86dd4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-83e86dd4 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-83e86dd4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-83e86dd4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-83e86dd4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-83e86dd4 .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-83e86dd4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-83e86dd4 .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-70fc3136{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-70fc3136 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-70fc3136 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-70fc3136 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-70fc3136 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-70fc3136 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-70fc3136 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-70fc3136{box-shadow: 0px 0px   #00000070 ;padding-top: 40px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;border-color: inherit;background-color: #04535c;;}.wp-block-uagb-advanced-heading.uagb-block-5959325e.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-5959325e.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-5959325e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5959325e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5959325e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5959325e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5959325e .uagb-heading-text{line-height: 1.2em;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1d75eb49{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-1d75eb49 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1d75eb49 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1d75eb49 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1d75eb49 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1d75eb49 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1d75eb49 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1d75eb49{box-shadow: 0px 0px   #00000070 ;padding-top: 25px;padding-bottom: 25px;padding-left: 25px;padding-right: 25px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 30px;margin-right: 30px;row-gap: 20px;column-gap: 20px;overflow: visible;border-color: inherit;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eff79e42{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-block-eff79e42 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eff79e42 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eff79e42 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-eff79e42 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-eff79e42 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eff79e42 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-eff79e42{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.uagb-block-15780b06.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-15780b06.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;text-align: center;}.uagb-block-15780b06.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-15780b06.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-15780b06.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-15780b06.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-15780b06.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-15780b06.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-15780b06.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-15780b06.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-15780b06.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-15780b06.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-15780b06.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-15780b06.wp-block-uagb-image--layout-default figure img:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-15780b06.wp-block-uagb-image--layout-overlay figure img:hover{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7e9c86a8{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-block-7e9c86a8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7e9c86a8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7e9c86a8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7e9c86a8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7e9c86a8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7e9c86a8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7e9c86a8{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.uagb-block-2c7fe1a1.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-2c7fe1a1.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;text-align: center;}.uagb-block-2c7fe1a1.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-2c7fe1a1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-2c7fe1a1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-2c7fe1a1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-2c7fe1a1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-2c7fe1a1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-2c7fe1a1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-2c7fe1a1.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-2c7fe1a1.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-2c7fe1a1.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-2c7fe1a1.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-2c7fe1a1.wp-block-uagb-image--layout-default figure img:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-2c7fe1a1.wp-block-uagb-image--layout-overlay figure img:hover{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a3f8e6a{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-block-6a3f8e6a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6a3f8e6a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6a3f8e6a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6a3f8e6a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6a3f8e6a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a3f8e6a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-6a3f8e6a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.uagb-block-b49db76c.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b49db76c.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;text-align: center;}.uagb-block-b49db76c.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b49db76c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-b49db76c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-b49db76c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-b49db76c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-b49db76c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-b49db76c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-b49db76c.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-b49db76c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-b49db76c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-b49db76c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-b49db76c.wp-block-uagb-image--layout-default figure img:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b49db76c.wp-block-uagb-image--layout-overlay figure img:hover{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0f60086f{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-block-0f60086f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0f60086f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0f60086f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0f60086f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0f60086f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0f60086f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-0f60086f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;column-gap: 20px;overflow: visible;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.uagb-block-14d7bd72.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-14d7bd72.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;text-align: center;}.uagb-block-14d7bd72.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-14d7bd72.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-14d7bd72.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-14d7bd72.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-14d7bd72.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-14d7bd72.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-14d7bd72.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-14d7bd72.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-14d7bd72.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-14d7bd72.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-14d7bd72.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-14d7bd72.wp-block-uagb-image--layout-default figure img:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-14d7bd72.wp-block-uagb-image--layout-overlay figure img:hover{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4d8a2e6f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4d8a2e6f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4d8a2e6f{padding-top: 150px;padding-bottom: 150px;padding-left: 50px;padding-right: 50px;margin-top:  !important;margin-bottom:  !important;background-size: cover;background-clip: padding-box;}.wp-block-uagb-container.uagb-block-4d8a2e6f::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-887a0016{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-887a0016 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 20px;}.wp-block-uagb-container.uagb-block-887a0016{padding-top: 80px;padding-bottom: 80px;padding-left: 50px;padding-right: 50px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;background-color: var(u002du002dast-global-color-5);;}.uagb-block-e8ce4646 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 20px;}.uagb-block-e8ce4646.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-e8ce4646.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-separator{margin-bottom: 20px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e8ce4646 .uagb-ifb-separator{width: 100px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e8ce4646 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e8ce4646 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e8ce4646 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e8ce4646 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e8ce4646 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-e8ce4646 .uagb-ifb-title-prefix{font-size: 18px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-284aab73{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-284aab73 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-284aab73{padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;background-color: #04535c;;}.uagb-block-9c86bd1f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0464bdde{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0464bdde > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-0464bdde{padding-top: 0px;padding-bottom: 30px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;background-color: #04535c;;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-502f40bb .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-502f40bb .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-502f40bb .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-502f40bb .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-502f40bb .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c1b6efa3 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c1b6efa3 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c1b6efa3 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c1b6efa3 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c1b6efa3 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-09c33d2e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-09c33d2e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-09c33d2e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-09c33d2e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-09c33d2e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-53c34ca2{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-53c34ca2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-53c34ca2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;}.uagb-block-83e86dd4.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-83e86dd4 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-83e86dd4 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-83e86dd4 .spectra-image-gallery__media{border-style: none;}.uagb-block-83e86dd4 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-70fc3136{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-70fc3136 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-70fc3136{padding-top: 40px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;background-color: #04535c;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1d75eb49{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1d75eb49 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1d75eb49{padding-top: 25px;padding-bottom: 25px;padding-left: 25px;padding-right: 25px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 30px;margin-right: 30px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eff79e42{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eff79e42 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-eff79e42{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;}.uagb-block-15780b06.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7e9c86a8{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7e9c86a8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7e9c86a8{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;background-clip: padding-box;}.uagb-block-2c7fe1a1.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a3f8e6a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a3f8e6a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6a3f8e6a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;}.uagb-block-b49db76c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0f60086f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0f60086f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-0f60086f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;}.uagb-block-14d7bd72.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4d8a2e6f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4d8a2e6f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4d8a2e6f{padding-top: 80px;padding-bottom: 80px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;background-size: cover;background-clip: padding-box;}.wp-block-uagb-container.uagb-block-4d8a2e6f::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-887a0016{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-887a0016 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;}.wp-block-uagb-container.uagb-block-887a0016{padding-top: 60px;padding-bottom: 60px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;row-gap: 0px;background-color: var(u002du002dast-global-color-5);;}.uagb-block-e8ce4646 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 20px;}.uagb-block-e8ce4646.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-e8ce4646.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-separator{margin-bottom: 20px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e8ce4646 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e8ce4646 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e8ce4646 .uagb-ifb-separator{width: 80px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e8ce4646 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e8ce4646 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e8ce4646 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e8ce4646.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-284aab73{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-284aab73 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-284aab73{padding-top: 30px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;background-color: #04535c;;}.uagb-block-9c86bd1f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0464bdde{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0464bdde > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0464bdde{padding-top: 0px;padding-bottom: 30px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;background-color: #04535c;;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-502f40bb .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-502f40bb .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-502f40bb .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-502f40bb .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-502f40bb .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-502f40bb.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c1b6efa3 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c1b6efa3 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c1b6efa3 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c1b6efa3 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c1b6efa3 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c1b6efa3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-09c33d2e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-09c33d2e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-09c33d2e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-09c33d2e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-09c33d2e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-09c33d2e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-53c34ca2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-53c34ca2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-53c34ca2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;}.uagb-block-83e86dd4.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-83e86dd4 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-83e86dd4 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-83e86dd4 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-83e86dd4 .spectra-image-gallery__media{border-style: none;}.uagb-block-83e86dd4 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-70fc3136{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-70fc3136 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-70fc3136{padding-top: 40px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;background-color: #04535c;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1d75eb49{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1d75eb49 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1d75eb49{padding-top: 25px;padding-bottom: 25px;padding-left: 25px;padding-right: 25px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 30px;margin-right: 30px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-eff79e42{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-eff79e42 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-eff79e42{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;flex-wrap: wrap;}.uagb-block-15780b06.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7e9c86a8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7e9c86a8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7e9c86a8{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;background-clip: padding-box;flex-wrap: wrap;}.uagb-block-2c7fe1a1.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a3f8e6a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a3f8e6a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6a3f8e6a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;flex-wrap: wrap;}.uagb-block-b49db76c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0f60086f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0f60086f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0f60086f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;flex-wrap: wrap;}.uagb-block-14d7bd72.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media (max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media (max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\n\";s:2:\"js\";s:19457:\"document.addEventListener(\"DOMContentLoaded\", function(){ \t\t\t\twindow.addEventListener( 'DOMContentLoaded', () => {\n\t\t\t\t\tconst blockScope = document.querySelector( '.uagb-block-83e86dd4' );\n\t\t\t\t\tif ( ! blockScope ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\tlet lightboxSwiper = null;\n\t\t\t\t\tlet thumbnailSwiper = null;\n\n\t\t\t\t\t\t\t\t\t\tlet lightboxSettings = {\"lazy\":true,\"slidesPerView\":1,\"navigation\":{\"nextEl\":\".uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .swiper-button-next\",\"prevEl\":\".uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .swiper-button-prev\"},\"keyboard\":{\"enabled\":true}};\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tlightboxSwiper = new Swiper( \".uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main\",\n\t\t\t\t\t\t{\"lazy\":true,\"slidesPerView\":1,\"navigation\":{\"nextEl\":\".uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .swiper-button-next\",\"prevEl\":\".uagb-block-83e86dd4+.spectra-image-gallery__control-lightbox .swiper-button-prev\"},\"keyboard\":{\"enabled\":true}}\t\t\t\t\t);\n\t\t\t\t\tloadLightBoxImages( blockScope, lightboxSwiper, null, {\"block_id\":\"83e86dd4\",\"classMigrate\":true,\"readyToRender\":true,\"tileSize\":255,\"mediaGallery\":[{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":200,\"width\":300,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2-300x200.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":683,\"width\":1024,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2-1024x683.jpg\",\"orientation\":\"landscape\"},\"trp-custom-language-flag\":{\"height\":12,\"width\":18,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2-18x12.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2.jpg\",\"height\":1000,\"width\":1500,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1854,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2.jpg\",\"alt\":\"hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2\",\"link\":\"https:\/\/intiqahotel.com\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-frontal-2\/\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":200,\"width\":300,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral-300x200.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":683,\"width\":1024,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral-1024x683.jpg\",\"orientation\":\"landscape\"},\"trp-custom-language-flag\":{\"height\":12,\"width\":18,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral-18x12.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral.jpg\",\"height\":1000,\"width\":1500,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1834,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral.jpg\",\"alt\":\"hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral\",\"link\":\"https:\/\/intiqahotel.com\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-lateral\/\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-bano-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":300,\"width\":200,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-bano-200x300.jpg\",\"orientation\":\"portrait\"},\"large\":{\"height\":1024,\"width\":683,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-bano-683x1024.jpg\",\"orientation\":\"portrait\"},\"trp-custom-language-flag\":{\"height\":12,\"width\":8,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-bano-8x12.jpg\",\"orientation\":\"portrait\"},\"full\":{\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-bano.jpg\",\"height\":2250,\"width\":1500,\"orientation\":\"portrait\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1835,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-bano.jpg\",\"alt\":\"hotel-intiqa-puno-peru-habitacion-matrimonial-bau00f1o\",\"link\":\"https:\/\/intiqahotel.com\/hotel-intiqa-puno-peru-habitacion-matrimonial-bano\/\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":200,\"width\":300,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet-300x200.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":683,\"width\":1024,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet-1024x683.jpg\",\"orientation\":\"landscape\"},\"trp-custom-language-flag\":{\"height\":12,\"width\":18,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet-18x12.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet.jpg\",\"height\":1000,\"width\":1500,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1838,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet.jpg\",\"alt\":\"hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet\",\"link\":\"https:\/\/intiqahotel.com\/hotel-intiqa-puno-peru-habitacion-matrimonial-vista-closet\/\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":200,\"width\":300,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion-300x200.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":683,\"width\":1024,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion-1024x683.jpg\",\"orientation\":\"landscape\"},\"trp-custom-language-flag\":{\"height\":12,\"width\":18,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion-18x12.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion.jpg\",\"height\":1000,\"width\":1500,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1837,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion.jpg\",\"alt\":\"hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion\",\"link\":\"https:\/\/intiqahotel.com\/hotel-intiqa-puno-peru-habitacion-matrimonial-recepcion\/\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-mesa-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":200,\"width\":300,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-mesa-300x200.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":683,\"width\":1024,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-mesa-1024x683.jpg\",\"orientation\":\"landscape\"},\"trp-custom-language-flag\":{\"height\":12,\"width\":18,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-mesa-18x12.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-mesa.jpg\",\"height\":1000,\"width\":1500,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1836,\"url\":\"https:\/\/intiqahotel.com\/wp-content\/uploads\/hotel-intiqa-puno-peru-habitacion-matrimonial-mesa.jpg\",\"alt\":\"hotel-intiqa-puno-peru-habitacion-matrimonial-mesa\",\"link\":\"https:\/\/intiqahotel.com\/hotel-intiqa-puno-peru-habitacion-matrimonial-mesa\/\",\"caption\":\"\"}],\"mediaIDs\":[1854,1834,1835,1838,1837,1836],\"imageDisplayCaption\":false,\"galleryImageSize\":\"full\",\"imageClickEvent\":\"lightbox\",\"columnsDesk\":2,\"columnsTab\":4,\"columnsMob\":4,\"feedMarginTop\":0,\"feedMarginRight\":0,\"feedMarginBottom\":0,\"feedMarginLeft\":0,\"imageBorderStyle\":\"none\",\"focusList\":[],\"focusListObject\":[],\"feedLayout\":\"grid\",\"galleryImageSizeTablet\":\"large\",\"galleryImageSizeMobile\":\"medium\",\"disableLazyLoad\":false,\"lightboxDisplayCaptions\":false,\"lightboxThumbnails\":false,\"lightboxDisplayCount\":false,\"lightboxCloseIcon\":\"xmark\",\"lightboxCaptionHeight\":50,\"lightboxCaptionHeightTablet\":\"\",\"lightboxCaptionHeightMobile\":\"\",\"lightboxIconSize\":24,\"lightboxIconSizeTablet\":\"\",\"lightboxIconSizeMobile\":\"\",\"captionVisibility\":\"hover\",\"captionDisplayType\":\"overlay\",\"imageCaptionAlignment\":\"center center\",\"imageCaptionAlignment01\":\"center\",\"imageCaptionAlignment02\":\"center\",\"imageDefaultCaption\":\"Sin leyenda\",\"captionPaddingTop\":8,\"captionPaddingRight\":8,\"captionPaddingBottom\":8,\"captionPaddingLeft\":8,\"captionPaddingTopTab\":8,\"captionPaddingRightTab\":8,\"captionPaddingBottomTab\":8,\"captionPaddingLeftTab\":8,\"captionPaddingTopMob\":8,\"captionPaddingRightMob\":8,\"captionPaddingBottomMob\":8,\"captionPaddingLeftMob\":8,\"captionPaddingUnit\":\"px\",\"captionPaddingUnitTab\":\"px\",\"captionPaddingUnitMob\":\"px\",\"captionPaddingUnitLink\":true,\"captionGap\":0,\"captionGapUnit\":\"px\",\"gridImageGap\":8,\"gridImageGapTab\":\"\",\"gridImageGapMob\":\"\",\"gridImageGapUnit\":\"px\",\"gridImageGapUnitTab\":\"px\",\"gridImageGapUnitMob\":\"px\",\"feedMarginTopTab\":\"\",\"feedMarginRightTab\":\"\",\"feedMarginBottomTab\":\"\",\"feedMarginLeftTab\":\"\",\"feedMarginTopMob\":\"\",\"feedMarginRightMob\":\"\",\"feedMarginBottomMob\":\"\",\"feedMarginLeftMob\":\"\",\"feedMarginUnit\":\"px\",\"feedMarginUnitTab\":\"px\",\"feedMarginUnitMob\":\"px\",\"feedMarginUnitLink\":true,\"carouselStartAt\":0,\"carouselSquares\":false,\"carouselLoop\":true,\"carouselAutoplay\":true,\"carouselAutoplaySpeed\":2000,\"carouselPauseOnHover\":true,\"carouselTransitionSpeed\":500,\"gridPages\":1,\"gridPageNumber\":1,\"feedPagination\":false,\"paginateUseArrows\":true,\"paginateUseDots\":true,\"paginateUseLoader\":true,\"paginateLimit\":9,\"paginateButtonAlign\":\"center\",\"paginateButtonText\":\"Subir mu00e1s imu00e1genes\",\"paginateButtonPaddingTop\":\"\",\"paginateButtonPaddingRight\":\"\",\"paginateButtonPaddingBottom\":\"\",\"paginateButtonPaddingLeft\":\"\",\"paginateButtonPaddingTopTab\":\"\",\"paginateButtonPaddingRightTab\":\"\",\"paginateButtonPaddingBottomTab\":\"\",\"paginateButtonPaddingLeftTab\":\"\",\"paginateButtonPaddingTopMob\":\"\",\"paginateButtonPaddingRightMob\":\"\",\"paginateButtonPaddingBottomMob\":\"\",\"paginateButtonPaddingLeftMob\":\"\",\"paginateButtonPaddingUnit\":\"px\",\"paginateButtonPaddingUnitTab\":\"px\",\"paginateButtonPaddingUnitMob\":\"px\",\"paginateButtonPaddingUnitLink\":true,\"imageEnableZoom\":true,\"imageZoomType\":\"zoom-in\",\"captionBackgroundEnableBlur\":false,\"captionBackgroundBlurAmount\":0,\"captionBackgroundBlurAmountHover\":5,\"lightboxEdgeDistance\":10,\"lightboxEdgeDistanceTablet\":\"\",\"lightboxEdgeDistanceMobile\":\"\",\"lightboxBackgroundEnableBlur\":true,\"lightboxBackgroundBlurAmount\":5,\"lightboxBackgroundColor\":\"rgba(0,0,0,0.75)\",\"lightboxIconColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionColor\":\"rgba(255,255,255,1)\",\"lightboxCaptionBackgroundColor\":\"rgba(0,0,0,1)\",\"captionLoadGoogleFonts\":false,\"captionFontFamily\":\"Default\",\"captionFontWeight\":\"\",\"captionFontStyle\":\"normal\",\"captionTransform\":\"\",\"captionDecoration\":\"none\",\"captionFontSizeType\":\"px\",\"captionFontSize\":\"\",\"captionFontSizeTab\":\"\",\"captionFontSizeMob\":\"\",\"captionLineHeightType\":\"em\",\"captionLineHeight\":\"\",\"captionLineHeightTab\":\"\",\"captionLineHeightMob\":\"\",\"loadMoreLoadGoogleFonts\":false,\"loadMoreFontFamily\":\"Default\",\"loadMoreFontWeight\":\"\",\"loadMoreFontStyle\":\"normal\",\"loadMoreTransform\":\"\",\"loadMoreDecoration\":\"none\",\"loadMoreFontSizeType\":\"px\",\"loadMoreFontSize\":\"\",\"loadMoreFontSizeTab\":\"\",\"loadMoreFontSizeMob\":\"\",\"loadMoreLineHeightType\":\"em\",\"loadMoreLineHeight\":\"\",\"loadMoreLineHeightTab\":\"\",\"loadMoreLineHeightMob\":\"\",\"lightboxLoadGoogleFonts\":false,\"lightboxFontFamily\":\"Default\",\"lightboxFontWeight\":\"\",\"lightboxFontStyle\":\"normal\",\"lightboxTransform\":\"\",\"lightboxDecoration\":\"none\",\"lightboxFontSizeType\":\"px\",\"lightboxFontSize\":\"\",\"lightboxFontSizeTab\":\"\",\"lightboxFontSizeMob\":\"\",\"lightboxLineHeightType\":\"em\",\"lightboxLineHeight\":\"\",\"lightboxLineHeightTab\":\"\",\"lightboxLineHeightMob\":\"\",\"captionBackgroundEffect\":\"none\",\"captionBackgroundEffectHover\":\"none\",\"captionBackgroundEffectAmount\":100,\"captionBackgroundEffectAmountHover\":0,\"captionColor\":\"rgba(255,255,255,1)\",\"captionColorHover\":\"rgba(255,255,255,1)\",\"captionBackgroundColor\":\"rgba(0,0,0,0.75)\",\"captionBackgroundColorHover\":\"rgba(0,0,0,0.75)\",\"overlayColor\":\"rgba(0,0,0,0)\",\"overlayColorHover\":\"rgba(0,0,0,0)\",\"captionSeparateColors\":false,\"paginateArrowDistance\":-24,\"paginateArrowDistanceUnit\":\"px\",\"paginateArrowSize\":24,\"paginateDotDistance\":8,\"paginateDotDistanceUnit\":\"px\",\"paginateLoaderSize\":18,\"paginateButtonTextColor\":\"\",\"paginateButtonTextColorHover\":\"\",\"paginateColor\":\"\",\"paginateColorHover\":\"\",\"imageBoxShadowColor\":\"\",\"imageBoxShadowHOffset\":0,\"imageBoxShadowVOffset\":0,\"imageBoxShadowBlur\":\"\",\"imageBoxShadowSpread\":\"\",\"imageBoxShadowPosition\":\"outset\",\"imageBoxShadowColorHover\":\"\",\"imageBoxShadowHOffsetHover\":0,\"imageBoxShadowVOffsetHover\":0,\"imageBoxShadowBlurHover\":\"\",\"imageBoxShadowSpreadHover\":\"\",\"imageBoxShadowPositionHover\":\"outset\",\"arrowBorderTopWidth\":4,\"arrowBorderLeftWidth\":4,\"arrowBorderRightWidth\":4,\"arrowBorderBottomWidth\":4,\"arrowBorderTopLeftRadius\":50,\"arrowBorderTopRightRadius\":50,\"arrowBorderBottomLeftRadius\":50,\"arrowBorderBottomRightRadius\":50,\"arrowBorderRadiusUnit\":\"px\",\"arrowBorderTopWidthTablet\":\"\",\"arrowBorderLeftWidthTablet\":\"\",\"arrowBorderRightWidthTablet\":\"\",\"arrowBorderBottomWidthTablet\":\"\",\"arrowBorderTopLeftRadiusTablet\":\"\",\"arrowBorderTopRightRadiusTablet\":\"\",\"arrowBorderBottomLeftRadiusTablet\":\"\",\"arrowBorderBottomRightRadiusTablet\":\"\",\"arrowBorderRadiusUnitTablet\":\"px\",\"arrowBorderTopWidthMobile\":\"\",\"arrowBorderLeftWidthMobile\":\"\",\"arrowBorderRightWidthMobile\":\"\",\"arrowBorderBottomWidthMobile\":\"\",\"arrowBorderTopLeftRadiusMobile\":\"\",\"arrowBorderTopRightRadiusMobile\":\"\",\"arrowBorderBottomLeftRadiusMobile\":\"\",\"arrowBorderBottomRightRadiusMobile\":\"\",\"arrowBorderRadiusUnitMobile\":\"px\",\"arrowBorderStyle\":\"none\",\"arrowBorderColor\":\"\",\"arrowBorderHColor\":\"\",\"btnBorderTopWidth\":\"\",\"btnBorderLeftWidth\":\"\",\"btnBorderRightWidth\":\"\",\"btnBorderBottomWidth\":\"\",\"btnBorderTopLeftRadius\":\"\",\"btnBorderTopRightRadius\":\"\",\"btnBorderBottomLeftRadius\":\"\",\"btnBorderBottomRightRadius\":\"\",\"btnBorderRadiusUnit\":\"px\",\"btnBorderTopWidthTablet\":\"\",\"btnBorderLeftWidthTablet\":\"\",\"btnBorderRightWidthTablet\":\"\",\"btnBorderBottomWidthTablet\":\"\",\"btnBorderTopLeftRadiusTablet\":\"\",\"btnBorderTopRightRadiusTablet\":\"\",\"btnBorderBottomLeftRadiusTablet\":\"\",\"btnBorderBottomRightRadiusTablet\":\"\",\"btnBorderRadiusUnitTablet\":\"px\",\"btnBorderTopWidthMobile\":\"\",\"btnBorderLeftWidthMobile\":\"\",\"btnBorderRightWidthMobile\":\"\",\"btnBorderBottomWidthMobile\":\"\",\"btnBorderTopLeftRadiusMobile\":\"\",\"btnBorderTopRightRadiusMobile\":\"\",\"btnBorderBottomLeftRadiusMobile\":\"\",\"btnBorderBottomRightRadiusMobile\":\"\",\"btnBorderRadiusUnitMobile\":\"px\",\"btnBorderStyle\":\"\",\"btnBorderColor\":\"\",\"btnBorderHColor\":\"\",\"imageBorderTopWidth\":\"\",\"imageBorderLeftWidth\":\"\",\"imageBorderRightWidth\":\"\",\"imageBorderBottomWidth\":\"\",\"imageBorderTopLeftRadius\":\"\",\"imageBorderTopRightRadius\":\"\",\"imageBorderBottomLeftRadius\":\"\",\"imageBorderBottomRightRadius\":\"\",\"imageBorderRadiusUnit\":\"px\",\"imageBorderTopWidthTablet\":\"\",\"imageBorderLeftWidthTablet\":\"\",\"imageBorderRightWidthTablet\":\"\",\"imageBorderBottomWidthTablet\":\"\",\"imageBorderTopLeftRadiusTablet\":\"\",\"imageBorderTopRightRadiusTablet\":\"\",\"imageBorderBottomLeftRadiusTablet\":\"\",\"imageBorderBottomRightRadiusTablet\":\"\",\"imageBorderRadiusUnitTablet\":\"px\",\"imageBorderTopWidthMobile\":\"\",\"imageBorderLeftWidthMobile\":\"\",\"imageBorderRightWidthMobile\":\"\",\"imageBorderBottomWidthMobile\":\"\",\"imageBorderTopLeftRadiusMobile\":\"\",\"imageBorderTopRightRadiusMobile\":\"\",\"imageBorderBottomLeftRadiusMobile\":\"\",\"imageBorderBottomRightRadiusMobile\":\"\",\"imageBorderRadiusUnitMobile\":\"px\",\"imageBorderColor\":\"\",\"imageBorderHColor\":\"\",\"mainTitleBorderTopWidth\":2,\"mainTitleBorderLeftWidth\":0,\"mainTitleBorderRightWidth\":0,\"mainTitleBorderBottomWidth\":2,\"mainTitleBorderTopLeftRadius\":\"\",\"mainTitleBorderTopRightRadius\":\"\",\"mainTitleBorderBottomLeftRadius\":\"\",\"mainTitleBorderBottomRightRadius\":\"\",\"mainTitleBorderRadiusUnit\":\"px\",\"mainTitleBorderTopWidthTablet\":\"\",\"mainTitleBorderLeftWidthTablet\":\"\",\"mainTitleBorderRightWidthTablet\":\"\",\"mainTitleBorderBottomWidthTablet\":\"\",\"mainTitleBorderTopLeftRadiusTablet\":\"\",\"mainTitleBorderTopRightRadiusTablet\":\"\",\"mainTitleBorderBottomLeftRadiusTablet\":\"\",\"mainTitleBorderBottomRightRadiusTablet\":\"\",\"mainTitleBorderRadiusUnitTablet\":\"px\",\"mainTitleBorderTopWidthMobile\":\"\",\"mainTitleBorderLeftWidthMobile\":\"\",\"mainTitleBorderRightWidthMobile\":\"\",\"mainTitleBorderBottomWidthMobile\":\"\",\"mainTitleBorderTopLeftRadiusMobile\":\"\",\"mainTitleBorderTopRightRadiusMobile\":\"\",\"mainTitleBorderBottomLeftRadiusMobile\":\"\",\"mainTitleBorderBottomRightRadiusMobile\":\"\",\"mainTitleBorderRadiusUnitMobile\":\"px\",\"mainTitleBorderStyle\":\"\",\"mainTitleBorderColor\":\"\",\"mainTitleBorderHColor\":\"\"}, thumbnailSwiper );\n\t\t\t\t\t\t\t\tconst regexCustomURL = new RegExp( '^((http|https):\/\/)(www.)?[a-zA-Z0-9@:%._\\+~#?&\/\/=]{2,256}\\.[a-z]{2,6}\\b([-a-zA-Z0-9@:%._\\+~#?&\/\/=]*)$' );\n\t\t\tconst customLinks = {};\n\t\t\tconst customLinksBehaviour = {};\n\n\t\t\tconst getCustomURL = ( caption ) => {\n\t\t\t\tif ( ! customLinks ) {\n\t\t\t\t\treturn undefined;\n\t\t\t\t}\n\t\t\t\tconst imageID = parseInt( caption.getAttribute( 'data-spectra-gallery-image-id' ) );\n\t\t\t\treturn ( regexCustomURL.test( customLinks[ imageID ] ) ? customLinks[ imageID ] : undefined );\n\t\t\t}\n\n\t\t\tconst getCustomLinkBehaviour = (caption) => {\n\t\t\t\tif (!customLinksBehaviour) {\n\t\t\t\t\treturn true;\n\t\t\t\t}\n\t\t\t\tconst imageId = parseInt(caption.getAttribute('data-spectra-gallery-image-id'));\n\t\t\t\treturn !(customLinksBehaviour[imageId] === true);\n\t\t\t};\n\n\t\t\tconst captions = lightboxSwiper.el.querySelectorAll( '.spectra-image-gallery__control-lightbox--caption' );\n\t\t\tfor ( let i = 0; i < captions.length; i++ ) {\n\t\t\t\tconst customURL = getCustomURL( captions[ i ] );\n\t\t\t\tif ( customURL ) {\n\t\t\t\t\tconst anchor = document.createElement( 'a' );\n\t\t\t\t\tanchor.target = getCustomLinkBehaviour( captions[ i ] ) ? '_blank' : '_self';\n\t\t\t\t\tanchor.rel = 'noopener noreferrer';\n\t\t\t\t\tanchor.href = customURL;\n\t\t\t\t\tanchor.innerHTML = captions[ i ].innerHTML;\n\t\t\t\t\tcaptions[ i ].textContent = '';\n\t\t\t\t\tcaptions[ i ].appendChild( anchor );\n\t\t\t\t}\n\t\t\t}\n\t\t\t\t\t\t} );\n\t\t\t });\";s:18:\"current_block_list\";a:18:{i:0;s:14:\"uagb\/container\";i:1;s:12:\"core\/heading\";i:3;s:13:\"uagb\/info-box\";i:4;s:25:\"uagb\/animations-extension\";i:6;s:10:\"uagb\/image\";i:7;s:21:\"uagb\/advanced-heading\";i:10;s:18:\"uagb\/image-gallery\";i:11;s:14:\"core\/paragraph\";i:12;s:11:\"core\/search\";i:13;s:10:\"core\/group\";i:14;s:17:\"core\/latest-posts\";i:15;s:20:\"core\/latest-comments\";i:16;s:13:\"core\/archives\";i:17;s:15:\"core\/categories\";i:18;s:9:\"core\/list\";i:19;s:14:\"core\/list-item\";i:20;s:10:\"core\/image\";i:21;s:14:\"core\/page-list\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778379598\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"_uag_css_file_name":["uag-css-1749.css"],"_uag_js_file_name":["uag-js-1749.js"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/intiqahotel.com\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Habitaci\u00f3n Matrimonial Habitaci\u00f3n Matrimonial Nuestrosreconocimientos En Intiqa, nos honra haber recibido el certificadode excelencia de TripAdvisor, reflejo de nuestrocompromiso con la calidad y la satisfacci\u00f3n denuestros hu\u00e9spedes. Agradecemos a la comunidadde viajeros por reconocer nuestro esfuerzo ypasi\u00f3n.","_links":{"self":[{"href":"https:\/\/intiqahotel.com\/en\/wp-json\/wp\/v2\/pages\/1749"}],"collection":[{"href":"https:\/\/intiqahotel.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/intiqahotel.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/intiqahotel.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intiqahotel.com\/en\/wp-json\/wp\/v2\/comments?post=1749"}],"version-history":[{"count":1,"href":"https:\/\/intiqahotel.com\/en\/wp-json\/wp\/v2\/pages\/1749\/revisions"}],"predecessor-version":[{"id":2683,"href":"https:\/\/intiqahotel.com\/en\/wp-json\/wp\/v2\/pages\/1749\/revisions\/2683"}],"up":[{"embeddable":true,"href":"https:\/\/intiqahotel.com\/en\/wp-json\/wp\/v2\/pages\/1390"}],"wp:attachment":[{"href":"https:\/\/intiqahotel.com\/en\/wp-json\/wp\/v2\/media?parent=1749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}